{"id":20663,"date":"2017-04-04T08:32:57","date_gmt":"2017-04-04T15:32:57","guid":{"rendered":"http:\/\/www.dragonframe.com\/?page_id=20663"},"modified":"2026-07-14T14:50:11","modified_gmt":"2026-07-14T21:50:11","slug":"dev","status":"publish","type":"page","link":"https:\/\/www.dragonframe.com\/de\/dev\/","title":{"rendered":"Downloads f\u00fcr den Entwicklungszweig"},"content":{"rendered":"<div class=\"pageTitle\">\n<h1>Entwicklungszweig <span class=\"white\">Downloads<\/span><\/h1>\n<\/div>\n\n\n\n<div class=\"sectionTitleBox\" style=\"border: none;\">\n<h1 class=\"sectionTitleBox\" style=\"text-align: left;\"><span style=\"color: #d99202;\">Dragonframe 2027.01<\/span>&nbsp;Entwicklung<\/h1>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"downloadButton\" data-no-translation=\"\"><a href='https:\/\/www.dragonframe.com\/download\/Dragonframe_2027.01.18322.pkg'>Dragonframe 2027.01.18322<br>macOS 13+<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"downloadButton\" data-no-translation=\"\"><a href='https:\/\/www.dragonframe.com\/download\/Dragonframe_2027.01.18322-Setup.exe'>Dragonframe 2027.01.18322<br>Windows 10+ (64-Bit only)<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"downloadButton\" data-no-translation=\"\"><a href='https:\/\/www.dragonframe.com\/download\/dragonframedev2027a_2027.01.18321_amd64.deb'>Dragonframe 2027.01.18321<br>Ubuntu 24.04+ 64-Bit<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"downloadButton\" data-no-translation=\"\"><a href='https:\/\/www.dragonframe.com\/download\/dragonframedev2027a-2027.01.18321-1.x86_64.rpm'>Dragonframe 2027.01.18321<br>Fedora 36+ 64-Bit<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"notes\">\n<h2>Versionshinweise<\/h2>\n<div style=\"display: none;\"><div class='subText'><h3>Dragonframe 2027.01.18322<\/h3>2027.01.18322\r<br\/>* Gr\u00f6\u00dfere hochaufl\u00f6sende Proxys korrekt anzeigen\r<br\/>\r<br\/>2027.01.18320\r<br\/>* Absturz beim Verschieben des Arc-Arbeitsbereichs zwischen Fenstern behoben\r<br\/>* Dem Lautst\u00e4rkeregler wurde ein 'x'-Symbol hinzugef\u00fcgt, wenn er stummgeschaltet ist.\r<br\/>* Gr\u00f6\u00dfere hochaufl\u00f6sende Proxys f\u00fcr die Wiedergabe zulassen (Einstellungen: Wiedergabe)\r<br\/>\r<br\/>2027.01.18305\r<br\/>* Steuerelemente f\u00fcr die Umlaufbahn hinzugef\u00fcgt, wenn sich das Rig im virtuellen Modus befindet\r<br\/>* Die Option 'Vollst\u00e4ndige Wiedergabe' (in den Hotkeys) wurde hinzugef\u00fcgt. Diese ignoriert Ein- und Ausstiegspunkte und spielt die gesamte Wiedergabe von Anfang bis Ende ab.\r<br\/>* Benachrichtige den Benutzer, wenn die Anlage die zul\u00e4ssigen Positionen f\u00fcr virtuelle Maschinen \u00fcberschreitet.\r<br\/>* Dem Bogenmen\u00fc wurde die Option 'Kreis\/Ellipse generieren\u2026' hinzugef\u00fcgt, um Kreise und Ellipsen zu erstellen.\r<br\/>* Den DMX-Kan\u00e4len wurde die Option 'Rampe' hinzugef\u00fcgt, um den Wert einer Lampe immer stufenlos zu erh\u00f6hen.\r<br\/>* Reibungslosere Encoder-Ansteuerung (erfordert aktualisierte Ger\u00e4te-Firmware)\r<br\/>* Das Arc-Videopanel kann in einem separaten Fenster angezeigt werden.\r<br\/>\r<br\/>2027.01.18220\r<br\/>* Die Python-Methoden scene.openFile und events.EventType.TakeOpened wurden hinzugef\u00fcgt.\r<br\/>* Die Funktion 'Mehrere Aufnahmen im Bild' unterst\u00fctzt nun auch Aufnahmen im R\u00fcckw\u00e4rtsgang korrekt.\r<br\/>\r<br\/>2027.01.18210\r<br\/>* Die Men\u00fcpunkte f\u00fcr benutzerdefinierte Skripte wurden entfernt, da sie durch Python ersetzt werden k\u00f6nnen.\r<br\/>* Die Python-Funktion `ui.addMenuOption` hat nun dict-Argumente hinzugef\u00fcgt, um die Werte f\u00fcr 'Shortcut' und 'Checked' festzulegen. Au\u00dferdem wurde `util.executeScript` hinzugef\u00fcgt, um bei Bedarf eine Benutzerskriptdatei direkt aufzurufen.\r<br\/>* Arc: Behoben: Virtuelle Achsen wurden in der Kanalliste der Achsenkonfiguration nicht mehr angezeigt.\r<br\/>* Arc: Problem behoben, dass das Gamepad-Men\u00fc unterhalb des Videopanels angezeigt wurde.\r<br\/>* Arc: Erm\u00f6glichte die Vorw\u00e4rtsbewegung mit Roboterarmen\r<br\/>* Linux: Fehlerbehebungen f\u00fcr den Wayland-Compositor\r<br\/>\r<br\/>2027.01.18180\r<br\/>* Men\u00fcpunkt &quot;Aufnahme | Saubere Aufnahme...&quot; hinzugef\u00fcgt\r<br\/>* Referenzszenenebenen verf\u00fcgen nun \u00fcber angewendete Videoassistenzebenen.\r<br\/>* Unterst\u00fctzung f\u00fcr Canon, EOS und C50 hinzugef\u00fcgt\r<br\/>* Unterst\u00fctzung f\u00fcr die Sensorreinigung des Canon hinzugef\u00fcgt (im Men\u00fc \u201eAufnahme\u201c). Funktioniert nur mit neueren R-Modellen.\r<br\/>* Ereignisse 'Aufnahme abgeschlossen' und 'Frame abgeschlossen' f\u00fcr die OSC-Ausgabe hinzugef\u00fcgt.\r<br\/>* Direkte Unterst\u00fctzung f\u00fcr das serielle Laika-Encoder-Protokoll hinzugef\u00fcgt.\r<br\/>\r<br\/>2027.01.18163\r<br\/>* Unterst\u00fctzung f\u00fcr Panasonic S5D hinzugef\u00fcgt\r<br\/>* Optionen f\u00fcr vertikale anamorphotische Entzerrung hinzugef\u00fcgt\r<br\/>* Python: util.executeInMainThread und executeInMainThreadWithResult hinzugef\u00fcgt\r<br\/>* Python: ui.setMenuOptionChecked und ui.isMenuOptionChecked hinzugef\u00fcgt\r<br\/>* Bogen: Positions- und Geschwindigkeitsdiagramme k\u00f6nnen vertikal skaliert werden\r<br\/>\r<br\/>2027.01.18138\r<br\/>Die Python-Integration l\u00e4dt Module aus einer durch Doppelpunkte getrennten Pfadliste, die mit der Umgebungsvariablen DRAGONFRAME_PATH angegeben wurde.\r<br\/>* Die Python-Konstanten dragonframe.ui setTopLevelMenuName und ui.Menu.UserTopLevel1\/2\/3 wurden hinzugef\u00fcgt, um Men\u00fcs der obersten Ebene hinzuzuf\u00fcgen.\r<br\/>\r<br\/>2027.01.18132\r<br\/>* Python- und PySide-Integration hinzugef\u00fcgt\r<br\/>* Feste Testaufnahmen mit externem Verschluss\r<br\/>* DMX: Option hinzugef\u00fcgt, standardm\u00e4\u00dfig einzelne Keyframe-Kan\u00e4le zu verwenden\r<br\/>* Link zur Benutzeranleitung korrigiert\r<br\/>\r<br\/>2027.01.18084\r<br\/>* Beliebige Referenzebenenrotation hinzugef\u00fcgt.\r<br\/>* Die Funktion 'Mehrfachaufnahme' verf\u00fcgt nun \u00fcber die Option \u201eAuf Rahmen zuschneiden\u201c.\r<br\/>* Shoot Multiple verf\u00fcgt \u00fcber die Option &quot;DMX nach Abschluss abschalten&quot;.\r<br\/>* DMX: Standardansichtsgr\u00f6\u00dfe ist FIT\r<br\/>* Mit Befehl-E (oder Strg-E unter Windows) kann zwischen Film und dem Arbeitsbereich, von dem aus gewechselt wurde (nicht immer Animation), umgeschaltet werden.\r<br\/>* Cine: Die Densitometer-Probenkreise bleiben an ihrer Position.\r<br\/>* Die Farbauswahl (f\u00fcr DMX-Kan\u00e4le oder Arc Axes) erscheint an der Stelle, an der Sie sie zuletzt verwendet haben.\r<br\/>* Bogen: Beim Hinzuf\u00fcgen einer neuen Achse springt der Kanal \u00fcber den zuletzt zugewiesenen hinaus.\r<br\/>* Behoben: Videostapelung + Vergr\u00f6\u00dferung f\u00fchrten zu unscharfer Videounterst\u00fctzung\r<br\/>* Nach R\u00fcckw\u00e4rtsaufnahmen deaktiviert Dragonframe nun die Moco-Synchronisation, bevor das Bild ans Ende der Sequenz bewegt wird, um ein Springen des Rigs zu vermeiden.\r<br\/>* Die Einstellung der Mausradgr\u00f6\u00dfe stoppt bei 400%, anstatt bis FIT zu gehen.\r<br\/>* Hinweis zum Abbrechen der R\u00fcckstellfunktion mit der ESC-Taste hinzugef\u00fcgt\r<br\/>* UR: Problem behoben, bei dem vPAN nicht \u00fcber -180 oder 180 Grad hinausgehen konnte.\r<br\/>* Problem behoben, bei dem der Inhalt des Referenz-Filmplayers beim Schlie\u00dfen und erneuten \u00d6ffnen verschwand.\r<br\/>\r<br\/>2027.01.18038\r<br\/>* Erkennen, wenn der UR-Roboter hinterherhinkt\r<br\/>\r<br\/>2027.01.17952\r<br\/>* Geschwindigkeit und Richtung des virtuellen Joggens in UR korrigiert\r<br\/>\r<br\/>2027.01.17948\r<br\/>* Versuch, Servojitter zu ber\u00fccksichtigen\r<br\/>\r<br\/>2027.01.17943\r<br\/>* Problem behoben, das zum Absturz des RTDE-Clients beim Verbinden mit einer ung\u00fcltigen IP-Adresse f\u00fchrte.\r<br\/>* Warnen Sie den Benutzer, wenn er Dragonframe \u00fcber Rosetta ausf\u00fchrt.\r<br\/>\r<br\/>2027.01.17937\r<br\/>* Ersetzen Sie den OpenGL-Code durch QRhi (Metal\/D3D11\/Vulkan)\r<br\/>* UR-Roboterarmunterst\u00fctzung<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"notes\">\n<h2>Neu in 2027.01<\/h2>\n<div style=\"display: none;\">\n<ul>\n \t<li>Das Grafiksystem verwendet unter macOS\/Windows\/Linux nun Metal\/D3D11\/Vulkan anstelle von OpenGL.<\/li>\n<li>Integriert <a href=\"\/de\/ufaqs\/python-integration\/\">Python + PySide-Unterst\u00fctzung<\/a><\/li>\n<li>Referenzebenen k\u00f6nnen nun beliebig gedreht werden.<\/li>\n<li>Die Gr\u00f6\u00dfe des hochaufl\u00f6senden Proxy-Wiedergabebildes kann unter Einstellungen | Wiedergabe konfiguriert werden.<\/li>\n<li>Mit Command+E (oder Control+E unter Windows\/Linux) kann zwischen Cinematography und dem Arbeitsbereich, in dem es zuletzt aktiviert wurde, umgeschaltet werden.\n<\/li><li>Arc: Unterst\u00fctzt einige Cobot-Roboterarme.<\/li>\n<li>Arc: Generische Joystick-Unterst\u00fctzung f\u00fcr Joggingmotoren<\/li>\n<li>Die Funktion \u2018Mehrere Aufnahmen\u2019 bietet die Option \u201eAuf Rahmen\u201c und die M\u00f6glichkeit, die DMX-Beleuchtung nach Abschluss der Aufnahmen abzuschalten.<\/li>\n<li>DMX: Bevorzugt wird es, DMX am Ende des Tages abzuschalten.<\/li>\n<li>DMX: Option zum Einstellen einer Rampenfunktion auf einzelnen Kan\u00e4len<\/li>\n<li>Arc: Vollst\u00e4ndige Fokuswerkzeuge hinzugef\u00fcgt, wenn die Fokusachse ausgew\u00e4hlt ist.<\/li>\n<li>Bogen: Die Option \u2018Kreis\/Ellipse generieren\u2026\u2019 wurde dem Bogenmen\u00fc hinzugef\u00fcgt.<\/li>\n<li>Arc: Orbit-Werkzeuge zu den Kamera-POV-Werkzeugen hinzugef\u00fcgt<\/li>\n<li>Arc: Das Videopanel kann zu einem eigenen Fenster werden<\/li>\n<li>Cine: Bild gem\u00e4\u00df alternativer Kompositionsanleitung exportieren<\/li>\n<li>Dem Aufnahmemen\u00fc wurde die Option \u2018Saubere Aufnahme\u2026\u2019 hinzugef\u00fcgt.<\/li>\n<li>Video-Assist-Level werden auf Referenzszenenebenen angewendet.<\/li>\n\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"sectionTitleBox\" style=\"border: none;\">\n<h1 class=\"sectionTitleBox\" style=\"text-align: left;\"><span style=\"color: #d99202;\">Dragonframe 2026.04<\/span>\u00a0Entwicklung<\/h1>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"downloadButton\" data-no-translation=\"\"><a href='https:\/\/www.dragonframe.com\/download\/Dragonframe_2026.04.18252.pkg'>Dragonframe 2026.04.18252<br>macOS 11+<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"downloadButton\" data-no-translation=\"\"><a href='https:\/\/www.dragonframe.com\/download\/Dragonframe_2026.04.18254-Setup.exe'>Dragonframe 2026.04.18254<br>Windows 10+ (64-Bit only)<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"downloadButton\" data-no-translation=\"\"><a href='https:\/\/www.dragonframe.com\/download\/dragonframedev2026b_2026.04.18254_amd64.deb'>Dragonframe 2026.04.18254<br>Ubuntu 22.04+ 64-Bit<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"downloadButton\" data-no-translation=\"\"><a href='https:\/\/www.dragonframe.com\/download\/dragonframedev2026b-2026.04.18254-1.x86_64.rpm'>Dragonframe 2026.04.18254<br>Fedora 36+ 64-Bit<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"notes\">\n<h2>Versionshinweise<\/h2>\n<div style=\"display: none;\"><div class='subText'><h3>Dragonframe 2026.04.18252<\/h3>2026.04.18252\r<br\/>* Behoben: Fehlerhaftes Verschieben der Hauptansicht im Animationsbereich beim Spiegeln oder Drehen\r<br\/>* Behobener potenzieller Zugriffsfehler bei der NDI-Ausgabe\r<br\/>\r<br\/>2026.04.18208\r<br\/>* Problem behoben, dass das Gamepad-Men\u00fc hinter dem Positionsdiagramm und dem Videopanel angezeigt wurde.\r<br\/>\r<br\/>2026.04.18180\r<br\/>* Unterst\u00fctzung f\u00fcr Canon, EOS und C50 hinzugef\u00fcgt\r<br\/>* Stellen Sie sicher, dass das Programm nicht auf die Verschlusszeitachse wartet (da diese sich nicht bewegt).\r<br\/>* Problem mit Videostapelung und LV-Magnetansichten, die zu unscharfen Bildern f\u00fchrten, behoben\r<br\/>* Behoben: Dragonframe sprang nach dem R\u00fcckw\u00e4rtsschie\u00dfen zum Ende der Sequenz.\r<br\/>* Problem behoben, dass die Referenzfilmplayer beim Dr\u00fccken der Schlie\u00dfen-Taste aktiv blieben.\r<br\/>\r<br\/>2026.04.18042\r<br\/>* Festes Fokusrechteck f\u00fcr Canon im 4K-Filmmodus\r<br\/>* Helligkeit des Tastaturfenstersymbols korrigiert\r<br\/>* Windows: Behebung eines potenziellen Absturzes beim Trennen der seriellen Schnittstelle\r<br\/>\r<br\/>2026.04.17968\r<br\/>* Unterst\u00fctzung f\u00fcr Canon, EOS und R6 V hinzugef\u00fcgt\r<br\/>* DMX-Direktwerte werden nach der Bearbeitung visuell aktualisiert.\r<br\/>\r<br\/>2026.04.17929\r<br\/>* Fehler beim Filmexport im Hochformat und beim Zusammenf\u00fcgen aller Ebenen behoben\r<br\/>\r<br\/>2026.04.17895\r<br\/>* Problem mit gegenseitigen St\u00f6rungen zwischen DMX- und ArcMoco-Ger\u00e4ten behoben\r<br\/>\r<br\/>2026.04.17847\r<br\/>* Verbesserte Behandlung von PTP\/libusb-Verbindungsproblemen unter macOS und Linux\r<br\/>* Problem behoben, das beim Herunterfahren von Digitalkameras unter Windows zu einem H\u00e4nger f\u00fchren konnte\r<br\/>\r<br\/>2026.04.17835\r<br\/>* DMX-Ger\u00e4tedefinitionen f\u00fcr Nanlite Forza 60CR, Pavoslim 60CL und Pavotube II 6XR hinzugef\u00fcgt.\r<br\/>* Die fehlerhafte Kameraposition beim Verschieben der Kamera durch Klicken im X-Sheet wurde behoben.\r<br\/>* Ein potenzieller Absturz beim Beenden des Programms \u00fcber das Kontextmen\u00fc des Docks wurde behoben.\r<br\/>* Tastenkombinationen f\u00fcr Dialogfeldschaltfl\u00e4chen unter macOS werden entfernt, da macOS diese weder unterst\u00fctzt noch erwartet.\r<br\/>\r<br\/>2026.04.17795\r<br\/>* Behoben: SOLO-Schaltfl\u00e4che im DMX-Ger\u00e4tekopf, wenn dieser zusammengeklappt ist und sich nicht im globalen Programm befindet.\r<br\/>* Dem Dialog &quot;Verschiebungstest&quot; wurde die Option &quot;Alles ausw\u00e4hlen&quot; hinzugef\u00fcgt.\r<br\/>* Zeigt die verwendeten Kanalnummern auf der Axis-Konfigurationsseite an\r<br\/>\r<br\/>2026.04.17704\r<br\/>* Unterst\u00fctzung f\u00fcr das sACN-Protokoll f\u00fcr DMX-Ausgabe hinzugef\u00fcgt.\r<br\/>* Mehrfachauswahl in den Dialogfeldern \u201eTests verwalten\u201c und \u201eTests verschieben\u201c zulassen\r<br\/>\r<br\/>2026.04.17584\r<br\/>* Der DMC-Lite-Code verbessert die Behandlung von USB-Unterbrechungen bei externer Stromversorgung.\r<br\/>* Unterst\u00fctzung f\u00fcr Sony-Modelle mit dem angeh\u00e4ngten Buchstaben \"A\" im Namen hinzugef\u00fcgt.\r<br\/>\r<br\/>2026.04.17437\r<br\/>* Zus\u00e4tzliche Protokollierung zur Fehlerbehebung bei Problemen mit der Dateiauswahl f\u00fcr den Filmexport hinzugef\u00fcgt.\r<br\/>\r<br\/>2026.04.17434\r<br\/>* macOS: Behebung eines Audioausfalls unter macOS 26\r<br\/>* Windows: Verbesserte Geschwindigkeit der D3D11-Videodekodierung\r<br\/>\r<br\/>2026.04.17405\r<br\/>* Bei Verwendung integrierter Grafikkarten sollte eine sinnvolle RAM-Menge f\u00fcr Referenzebenentexturen ermittelt werden.\r<br\/>* Windows: Korrektur von Frame-Fehlern und Bildauff\u00fcllung durch hardwarebeschleunigte Dekodierung der D3D-Referenzebene\r<br\/>* Ein m\u00f6glicher Absturz beim Wechsel des Ger\u00e4tetyps der Bewegungssteuerungsverbindung wurde behoben.\r<br\/>\r<br\/>2026.04.17383\r<br\/>* macOS LibUSB-Kameraverbindung \u2013 Versuch, die unterbrochene Kommunikation wiederherzustellen\r<br\/>\r<br\/>2026.04.17375\r<br\/>* Die Ansicht ausgeblendeter Frames in der Zeitleiste wurde aktualisiert, um sie besser sichtbar zu machen.\r<br\/>* Stellen Sie sicher, dass die schwebende Werkzeugpalette immer innerhalb der Grenzen der Animationsansicht bleibt.\r<br\/>* Stellen Sie sicher, dass die Schrittfolge auch dann funktioniert, wenn das Audioger\u00e4t die Wiedergabe nicht startet.\r<br\/>* Grafikfehler auf Windows 11 ARM-Rechnern behoben\r<br\/>\r<br\/>2026.04.17322\r<br\/>* Feste Kamera verbindet sich automatisch mit mehreren Kameras\r<br\/>* Zeigt dem Benutzer Fehlermeldungen an, wenn XML-Importe fehlschlagen.\r<br\/>* Definition f\u00fcr Prolights ECL Cyclorama-Leuchten hinzugef\u00fcgt\r<br\/>* BriteQ Profile HD- und Profile WW-Ger\u00e4tedefinitionen hinzugef\u00fcgt\r<br\/>\r<br\/>2026.04.17290\r<br\/>* Windows \u2013 Ein potenzieller Absturz beim Verschieben von Arbeitsbereichen zwischen Fenstern wurde behoben.\r<br\/>* Zeigt eine Meldung auf dem Bildschirm an, wenn der Benutzer mit gedr\u00fcckter Alt-\/Wahltaste auf Frames klickt, um diese ein-\/auszublenden.\r<br\/>\r<br\/>2026.04.17272\r<br\/>* DMX-Festversatz f\u00fcr Universum-, Wartungs- und Blip-Men\u00fcs\r<br\/>* Verhindern, dass ein Haltepunkt durch ausgeblendete Frames gezogen wird\r<br\/>* Verhindern Sie, dass ausgeblendete Frames im \u00dcberschreibungsmodus verschoben werden k\u00f6nnen.\r<br\/>* Webcam-Geschwindigkeit bei Einstellungsparametern\r<br\/>* Moco-Protokollierungsfenster entfernen\r<br\/>\r<br\/>2026.04.17184\r<br\/>* Korrekte Definitionen f\u00fcr ARRI-Leuchten wiederhergestellt.\r<br\/>* Nanlite Forza 60B II wurde ein Effektmodus hinzugef\u00fcgt.\r<br\/>* Linux aktualisiert automatisch die udev-Regeln f\u00fcr virtuelle COM-Port-Ger\u00e4te\r<br\/>\r<br\/>2026.04.17164\r<br\/>* Erm\u00f6glichen Sie die Verwendung der Wiedergabetaste (0) \u00fcber den Ziffernblock im Audioarbeitsbereich.\r<br\/>* Ein potenzieller Absturz wurde behoben, der auftrat, wenn macOS den Namen der Digitalkamera \u00e4nderte (\"Canon Digital Camera\" -&gt; \"Canon EOS 6D\").\r<br\/>* Unter Arch Linux zeigt Dragonframe die Ergebnisse der Aktualisierung vor dem Beenden an.\r<br\/>\r<br\/>2026.04.17150\r<br\/>* Problem behoben, das zum Absturz von macOS 26 beim Wechsel in den Ruhezustand f\u00fchrte.\r<br\/>* Versuch, die Referenzfilmdateien erneut zu verkn\u00fcpfen, wenn die Datei vor\u00fcbergehend verschwindet.\r<br\/>* Die Darstellung von Miniaturansichten in der Zeitleiste wurde verbessert, wenn die Skala auf Sekunden verkleinert wird.\r<br\/>* Speichern Sie Referenz-Filmminiaturen auf der Festplatte, um einen schnelleren Zugriff zu erm\u00f6glichen.\r<br\/>* Der Fehler mit der automatischen Umschaltfunktion in Arc wurde behoben, die f\u00e4lschlicherweise den Umschaltmodus \u00e4nderte.\r<br\/>\r<br\/>2026.04.17125\r<br\/>* DMX: Korrekte Behandlung von Gruppen-Solo\/Ein\/Aus mit Ger\u00e4te-Unterger\u00e4ten\r<br\/>* Automatisches Speichern w\u00e4hrend der Bewegungssteuerung beim Joggen\/Browsen deaktivieren\r<br\/>* \u00dcberarbeitung der Kamera-Freeze-Pr\u00fcfung zur Vermeidung von Fehlalarmen\r<br\/>\r<br\/>2026.04.17111\r<br\/>* DMX: Definitionen f\u00fcr Nanlux Storm 400X- und 700X-Scheinwerfer hinzugef\u00fcgt.\r<br\/>* DMX: Leistungseinbu\u00dfen bei hoher Keyframe-Dichte behoben. Neue Leistungsverbesserungen beim Rendering hinzugef\u00fcgt.\r<br\/>* DMX: Fehler bei \"Keyframe vorher einf\u00fcgen\" im Tabellenmodus behoben\r<br\/>\r<br\/>2026.04.17090\r<br\/>* Die Schaltfl\u00e4che 'BASH' in der Kinematografie wurde ge\u00e4ndert und ein Fehler behoben, durch den sie zwar anklickbar, aber nicht sichtbar war.\r<br\/>\r<br\/>2026.04.17064\r<br\/>* OSC-Meldungen zum Festlegen von Achsenbegrenzungen, Nullpunkt und Referenzpunkt hinzugef\u00fcgt.\r<br\/>\r<br\/>2026.04.17050\r<br\/>* Ein potenzieller Absturz beim Arri Image SDK auf Intel Xeon Prozessoren wurde behoben.\r<br\/>* Problem beim Laden von HEIF-Dateien behoben und Unterst\u00fctzung f\u00fcr Windows und Linux hinzugef\u00fcgt\r<br\/>* Autofokus f\u00fcr Fujifilm-Kameras hinzugef\u00fcgt\r<br\/>\r<br\/>2026.04.17032\r<br\/>* Live-View-Vergr\u00f6\u00dferung des Fujifilm-Griffs im 35-mm-Crop-Modus\r<br\/>* Fujifilm warnt den Benutzer, wenn er sich im falschen Film-\/Standbildmodus befindet.\r<br\/>\r<br\/>2026.04.17027\r<br\/>* Sony A7 V hinzugef\u00fcgt (ungetestet)\r<br\/>* DMX stellt sicher, dass das Bearbeitungsfeld f\u00fcr Name, Kanal oder Wert an der richtigen Stelle angezeigt wird und mit dem Benutzer scrollt.\r<br\/>\r<br\/>2026.04.17022\r<br\/>* Fehler beim A\/B-Test behoben, der auftrat, wenn beide Bilder gedreht wurden\r<br\/>* Problem behoben, bei dem das A\/B-Tool im DMX-Arbeitsbereich nicht korrekt dargestellt wurde\r<br\/>\r<br\/>2026.04.17018\r<br\/>* Das A\/B-Tool kann Bilder mit unterschiedlichen Ausrichtungen verarbeiten.\r<br\/>* Stellen Sie sicher, dass die Schieberegler der schwebenden Palette nach dem Ausblenden keine Mausber\u00fchrungen mehr empfangen.\r<br\/>* Die Nanlux Evoke 600C-Leuchte wurde hinzugef\u00fcgt.\r<br\/>* DMX: Die Option 'Geerbte Kan\u00e4le zusammenf\u00fchren' wurde dem Programmmen\u00fc hinzugef\u00fcgt.\r<br\/><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"notes\">\n<h2>Neu im April 2026<\/h2>\n<div style=\"display: none;\">\n<ul>\n <li>Die Darstellung von Miniaturansichten in der Zeitleiste wurde verbessert, wenn die Skala auf Sekunden verkleinert wird.<\/li>\n<li>Speichern Sie Referenz-Filmminiaturen auf der Festplatte, um einen schnelleren Zugriff zu erm\u00f6glichen.<\/li>\n  <li>DMX: Die Option \u2018Geerbte Kan\u00e4le zusammenf\u00fchren\u2019 wurde dem Programmmen\u00fc hinzugef\u00fcgt.<\/li>\n<li>DMX: Unterst\u00fctzung f\u00fcr das sACN-Protokoll hinzugef\u00fcgt. F\u00fcgen Sie unter Szene | Verbindungen eine Verbindung hinzu, w\u00e4hlen Sie \u2018sACN DMX\u2019 als Typ und geben Sie eine Multicast- oder Unicast-Adresse ein. Optional k\u00f6nnen Sie eine sACN-Priorit\u00e4tsstufe angeben. Beispiele:<br><code>239.255.0.1<\/code><br><code>239.255.0.1 p=200<\/code><br><code>192.168.0.1:10<\/code> (Universum = 10)<\/li>\n \t<li>Wir arbeiten daran, den meisten Kameras eine Autofokus-Option f\u00fcr die anf\u00e4ngliche Fokussierung hinzuzuf\u00fcgen.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"sectionTitleBox\" style=\"border: none;\">\n<h1 class=\"sectionTitleBox\"><span style=\"color: #d99202;\">DMC-32\/DMC-16\/DMC+<\/span> Ressourcen<\/h1>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<p class=\"downloadHeader\">DMC-32-Firmware<\/p>\n<div class=\"downloadButton\" data-no-translation=\"\"><a href=\"https:\/\/www.dragonframe.com\/download\/DMC32-4.9.0.flash.zip\">DMC32-4.9.0.flash.zip<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<p class=\"downloadHeader\">zDMC-Firmware f\u00fcr DF4+<\/p>\n<div class=\"downloadButton\" data-no-translation=\"\"><a href=\"https:\/\/www.dragonframe.com\/download\/zDMC-4.9.0.flash.zip\">zDMC-4.9.0.flash.zip<\/a><\/div>\n<p style=\"font-size: 11px; line-height: 15px;\">F\u00fcr DMC-16 oder DMC+ mit \u201ez\u201c-Upgradekarte. Der Status \u201eSzene|Verbindungen\u201c zeigt \u201ezDMC-16\u201c oder \u201ezDMC+\u201c.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Development Branch Downloads Dragonframe 2027.01&nbsp;Development Release Notes New In 2027.01 Graphics system now uses Metal\/D3D11\/Vulkan on macOS\/Windows\/Linux, instead of OpenGL Integrated Python + PySide support Reference layers can now be arbitrarily rotated. Hi-res proxy playback image size is configurable in Preferences|Playback. Command+E (or Control+E on Windows\/Linux) toggle between Cinematography and whatever workspace you last activated &#8230; <a title=\"Downloads f\u00fcr den Entwicklungszweig\" class=\"read-more\" href=\"https:\/\/www.dragonframe.com\/de\/dev\/\" aria-label=\"Weitere Informationen \u00fcber Development Branch Downloads\">Mehr lesen<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-20663","page","type-page","status-publish","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/www.dragonframe.com\/de\/wp-json\/wp\/v2\/pages\/20663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dragonframe.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dragonframe.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dragonframe.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dragonframe.com\/de\/wp-json\/wp\/v2\/comments?post=20663"}],"version-history":[{"count":28,"href":"https:\/\/www.dragonframe.com\/de\/wp-json\/wp\/v2\/pages\/20663\/revisions"}],"predecessor-version":[{"id":74062,"href":"https:\/\/www.dragonframe.com\/de\/wp-json\/wp\/v2\/pages\/20663\/revisions\/74062"}],"wp:attachment":[{"href":"https:\/\/www.dragonframe.com\/de\/wp-json\/wp\/v2\/media?parent=20663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}